{"id":557,"date":"2018-10-15T15:00:19","date_gmt":"2018-10-15T13:00:19","guid":{"rendered":"http:\/\/www.smarttarif24.de\/Blog\/?p=557"},"modified":"2018-10-12T17:53:01","modified_gmt":"2018-10-12T15:53:01","slug":"selfie-hype-was-ist-ein-selfie","status":"publish","type":"post","link":"https:\/\/www.smarttarif24.de\/blog\/2018\/10\/15\/selfie-hype-was-ist-ein-selfie\/","title":{"rendered":"Selfie Hype &#8211; Was ist ein Selfie?"},"content":{"rendered":"<p>Seien wir mal ehrlich, der Selfie ist in unsere heutigen zeit nicht mehr wegzudenken! Egal ob im Urlaub, mit Freunden im Cafe oder zuhause mit den liebsten man h\u00e4lt die Momente fest und teilt sie im Socialmedia. Aber hab ihr euch eigentlich mal gefragt was ein Selfie \u00fcberhaupt ist?<\/p>\n<h2>Was ist ein Selfie?<\/h2>\n<p>Ein Selfie ist ein Selbstportrait, das meistens mit dem Smartphone fotografiert wird. Der Begriff Selfie kommt aus dem englischsprachigen Raum und leitet sich daher von dem englischen Wort \u201e<i>self<\/i>\u201c, zu Deutsch \u201e<i>selber<\/i>\u201c oder \u201e<i>selbst<\/i>\u201c ab. Es spielt darauf an, dass das Selfie den Fotografierenden\u00a0<i>selbst<\/i>\u00a0darstellt.<\/p>\n<h2>Wer ist der Erfinder des Selfies?<\/h2>\n<figure style=\"width: 150px\" class=\"wp-caption alignright\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.handysektor.de\/fileadmin\/_migrated\/RTE\/RTEmagicC_Unidentified_woman_taking_her_own_photograph_using_a_mirror_and_a_box_camera__roughly_1900.jpg.jpg\" alt=\"Selbstfotografie einer Frau im Spiegel von 1900\" width=\"150\" height=\"190\" data-htmlarea-file-table=\"sys_file\" data-htmlarea-file-uid=\"260\" \/><figcaption class=\"wp-caption-text\">Quelle: Wikipedia \/ Unbekannt<\/figcaption><\/figure>\n<p>Die ersten Formen des Selfies k\u00f6nnen schon in der ersten H\u00e4lfte des 19. Jahrhunderts\u00a0nachgewiesen werden. In unserem Beispiel nutzt die Frau um das Jahr 1900 dazu einen Spiegel und eine Boxkamera.<\/p>\n<p>Der Name \u201eSelfie\u201c wurde zum ersten Mal am 13. September 2002 in einem australischen Internet-Forum\u00a0genutzt. Es scheint also, als h\u00e4tte ein Australier den Begriff \u201eSelfie\u201c erfunden.\u00a0Bis Selfies zum Trend wurden, sind aber noch einige Jahre vergangen.<\/p>\n<p>&nbsp;<\/p>\n<h2>Wie kam es zum Selfie-Hype?<\/h2>\n<p>Obwohl das Selfie anscheinend schon lange bekannt ist, wurde es doch erst in den letzten ein bis zwei Jahren wirklich ber\u00fchmt. Ein Grund daf\u00fcr ist sicherlich die steigende Anzahl der Smartphone-Nutzer und auch die rasante technologische Entwicklung der Kameras in Smartphones. Denn wenn wir auch heute noch Selfies mit einer Boxkamera machen m\u00fcssten, g\u00e4be es sie sicher nicht so h\u00e4ufig. Da sind die mittlerweile guten Frontkameras bei Smartphones praktischer. Au\u00dferdem scheinen auch Stars erst jetzt entdeckt zu haben, wieviel Aufmerksamkeit sie mit einem einfachen Selfie erregen k\u00f6nnen. Schlussendlich haben aber sicher auch soziale Netzwerke wie Instagram, Facebook und Twitter ihren Teil zum Selfie-Hype beigetragen.<\/p>\n<h2>Welche Selfie-Arten kennst du?<\/h2>\n<figure id=\"attachment_558\" aria-describedby=\"caption-attachment-558\" style=\"width: 393px\" class=\"wp-caption alignright\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-558\" src=\"http:\/\/www.smarttarif24.de\/Blog\/wp-content\/uploads\/2018\/10\/40963904_m.jpg\" alt=\"Selfie Hype - Was ist ein Selfie?\" width=\"393\" height=\"393\" srcset=\"https:\/\/www.smarttarif24.de\/blog\/wp-content\/uploads\/2018\/10\/40963904_m.jpg 2048w, https:\/\/www.smarttarif24.de\/blog\/wp-content\/uploads\/2018\/10\/40963904_m-150x150.jpg 150w, https:\/\/www.smarttarif24.de\/blog\/wp-content\/uploads\/2018\/10\/40963904_m-300x300.jpg 300w, https:\/\/www.smarttarif24.de\/blog\/wp-content\/uploads\/2018\/10\/40963904_m-768x768.jpg 768w, https:\/\/www.smarttarif24.de\/blog\/wp-content\/uploads\/2018\/10\/40963904_m-1024x1024.jpg 1024w\" sizes=\"(max-width: 393px) 100vw, 393px\" \/><figcaption id=\"caption-attachment-558\" class=\"wp-caption-text\">Quelle:123rf.com \/ zmiter<\/figcaption><\/figure>\n<p>Vom Selfie hat mittlerweile jeder schon mal geh\u00f6rt, aber kennst du auch schon diese verr\u00fcckten Abwandlungen vom Selfie?<\/p>\n<p><b>Relfie:<\/b>\u00a0Ein Selfie von einem P\u00e4rchen (\u201eBeziehung\u201c, engl.\u00a0<i>\u201erelationship\u201c<\/i>).<\/p>\n<p><b>Ussie:<\/b>\u00a0Ein Selfie von dir und anderen Personen (\u201ewir\u201c, engl. \u201e<i>us<\/i>\u201c). Aber Vorsicht: Denke an das\u00a0Recht am eigenen Bild, wenn du Selfies mit anderen Personen machst!<\/p>\n<p><b>Shelfie:\u00a0<\/b>Ein Selfie von einem B\u00fccherregal (\u201eRegal\u201c, engl. \u201e<i>shelf\u201c<\/i>).<\/p>\n<p><b>Suglie<\/b>: Ein Selfie, in dem man versucht so h\u00e4sslich wie m\u00f6glich auszusehen (\u201eh\u00e4sslich\u201c, engl. \u201e<i>ugly\u201c<\/i>).<\/p>\n<p>Diese und viele weitere lustige Abwandlungen des Selfies gibt es bereits und es kommen st\u00e4ndig neue dazu.<\/p>\n<h2>Bitte nicht nachmachen!<\/h2>\n<p>Wie bei jedem Trend gibt es leider auch Menschen, die ein bisschen zu weit gehen. Folgende Selfies sind definitiv nicht zum Nachahmen gedacht!<\/p>\n<p><b>In Krankenh\u00e4usern oder bei Krisen:\u00a0<\/b>Ein Selfie in einem Krankenhaus, bei Unf\u00e4llen oder anderen Katastrophen ist einfach nur geschmacklos! Auch Gedenkst\u00e4tten geh\u00f6ren leider zu einem beliebten Selfie-Ziel. Hier sollte aber definitiv nicht dein Gesicht im Vordergrund stehen!<\/p>\n<p><b>Beim Autofahren:<\/b>\u00a0Wer ein Selfie beim Autofahren macht gef\u00e4hrdet nicht nur sich selbst, sondern auch andere Menschen, die am Stra\u00dfenverkehr teilnehmen. Deshalb gilt beim Autofahren: H\u00e4nde weg vom Smartphone!<\/p>\n<p><b>An gef\u00e4hrlichen Orten<\/b>: Kaum zu glauben: ein Paar st\u00fcrzte in Portugal von einer Klippe, weil sie ein spektakul\u00e4res\u00a0Selfie machen wollten. Auch Selfies auf Zuggleisen scheinen beliebt zu sein. Doch kein Selfie ist es wert, sich daf\u00fcr in Gefahr zu begeben. Urlaubseindr\u00fccke kannst du auch als Erinnerungen abspeichern\u00a0und auf Gleisen haben nur Z\u00fcge etwas verloren.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/vg02.met.vgwort.de\/na\/a16fb60b15114d978267f890ff8722ac\" alt=\"\" width=\"1\" height=\"1\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seien wir mal ehrlich, der Selfie ist in unsere heutigen zeit nicht mehr wegzudenken! Egal ob im Urlaub, mit Freunden im Cafe oder zuhause mit&hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,3,5],"tags":[223,222,13,63,99,193],"_links":{"self":[{"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/posts\/557"}],"collection":[{"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/comments?post=557"}],"version-history":[{"count":7,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/posts\/557\/revisions"}],"predecessor-version":[{"id":667,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/posts\/557\/revisions\/667"}],"wp:attachment":[{"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/media?parent=557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/categories?post=557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/tags?post=557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}