{"id":46,"date":"2018-03-07T11:30:00","date_gmt":"2018-03-07T10:30:00","guid":{"rendered":"http:\/\/www.smarttarif24.de\/BLOG\/?p=46"},"modified":"2018-03-07T11:31:04","modified_gmt":"2018-03-07T10:31:04","slug":"huawei-p20-preis-geleakt","status":"publish","type":"post","link":"https:\/\/www.smarttarif24.de\/blog\/2018\/03\/07\/huawei-p20-preis-geleakt\/","title":{"rendered":"Huawei P20 Preis geleakt"},"content":{"rendered":"<figure id=\"attachment_47\" aria-describedby=\"caption-attachment-47\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-47\" src=\"http:\/\/www.smarttarif24.de\/BLOG\/wp-content\/uploads\/2018\/03\/huawei-p20-27-maerz-praesentiert-226820-300x225.jpg\" alt=\"Huaweip20\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.smarttarif24.de\/blog\/wp-content\/uploads\/2018\/03\/huawei-p20-27-maerz-praesentiert-226820-300x225.jpg 300w, https:\/\/www.smarttarif24.de\/blog\/wp-content\/uploads\/2018\/03\/huawei-p20-27-maerz-praesentiert-226820.jpg 598w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-47\" class=\"wp-caption-text\">Quelle: Huawei<\/figcaption><\/figure>\n<p><strong>Huawei wird am 27. M\u00e4rz einen Nachfolger f\u00fcr sein Top-Smartphone\u00a0Huawei P10\u00a0enth\u00fcllen. Wie bereits vermutet, wird das Modell Huawei P20 hei\u00dfen. Das hat der chinesische Hersteller nun best\u00e4tigt.<\/strong><\/p>\n<p>So soll das P20 Lite f\u00fcr knapp <strong>369 Euro<\/strong> in den Handel kommen, das P20 wird <strong>679 Euro<\/strong> kosten und f\u00fcr das P20 Pro verlangt Huawei <strong>899 Euro<\/strong>.<\/p>\n<h1>Huawei P20 Pro mit Triple-Kamera<\/h1>\n<p>Sowohl unter dem 5,7 Zoll gro\u00dfen Display des Huawei P20 als auch dem 6 Zoll gro\u00dfen Screen des P20 Plus kommt mit dem Kirin 970 der aktuelle Highend Chip von Huawei zum Einsatz. Auf der R\u00fcckseite soll sich beim Huawei P20 Pro eine Triple-Kamera, bestehend aus einem RGB-Sensor mit 12 Megapixel und einem Monochrom-Sensor mit 16-Megapixel befinden. Beim Vorg\u00e4nger war hingegen nur eine Dual-Kamera mit Monochrom-Sensor.<\/p>\n<p>Weitere Informationen folgen demn\u00e4chst auf<a href=\"http:\/\/www.smarttarif24.de\"> www.smarttarif24.de<\/a><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"pl\" dir=\"ltr\">Huawei P20 = 679,xx Euro<br \/>Huawei P20 Pro = 899,xx Euro<br \/>Huawei P20 Lite = 369,xx Euro<\/p>\n<p>&mdash; Roland Quandt (@rquandt) <a href=\"https:\/\/twitter.com\/rquandt\/status\/970572443919290369?ref_src=twsrc%5Etfw\">March 5, 2018<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Preis von Roland Quandt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Huawei wird am 27. M\u00e4rz einen Nachfolger f\u00fcr sein Top-Smartphone\u00a0Huawei P10\u00a0enth\u00fcllen. Wie bereits vermutet, wird das Modell Huawei P20 hei\u00dfen. Das hat der chinesische Hersteller&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"_links":{"self":[{"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/posts\/46"}],"collection":[{"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/comments?post=46"}],"version-history":[{"count":2,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/posts\/46\/revisions"}],"predecessor-version":[{"id":49,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/posts\/46\/revisions\/49"}],"wp:attachment":[{"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/media?parent=46"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/categories?post=46"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/tags?post=46"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}