{"id":3198,"date":"2022-05-12T11:00:00","date_gmt":"2022-05-12T09:00:00","guid":{"rendered":"https:\/\/www.smarttarif24.de\/blog\/?p=3198"},"modified":"2022-05-11T17:01:13","modified_gmt":"2022-05-11T15:01:13","slug":"instagram-bald-auch-nft-kunstwerke-auf-der-platform","status":"publish","type":"post","link":"https:\/\/www.smarttarif24.de\/blog\/2022\/05\/12\/instagram-bald-auch-nft-kunstwerke-auf-der-platform\/","title":{"rendered":"Instagram: bald auch NFT Kunstwerke auf der Platform?"},"content":{"rendered":"\n<p id=\"pageIndex_1\">Was ist wieder bei Instagram los? Bald euch ein Kunstportal? Eine ausgew\u00e4hlte Gruppe von K\u00fcnstlern und Sammlern aus den USA soll in K\u00fcrze die M\u00f6glichkeit haben, ihre NFT-Kunstwerke auf der Social Media Plattform zu pr\u00e4sentieren. Der meta Chef h\u00f6chst pers\u00f6nlich Mark Zuckerberg und Instagram-Chef Adam Mosseri haben das auf Facebook und Twitter angek\u00fcndigt. Non-Fungible Token, die Kurzform NFT, die in der Szene aktuell in aller munde sind und boomen, erm\u00f6glichen es, digitale Inhalte mit einem nicht austauschbaren Besitzzertifikat zu versehen. Technisch gesehen handelt es sich bei NFTs um Eintr\u00e4ge in einem endlos fortgeschriebenen Digitalregister, der sogenannten Blockchain.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.smarttarif24.de\/blog\/wp-content\/uploads\/2022\/03\/New-update-1024x1024.png\" alt=\"\" class=\"wp-image-3102\" srcset=\"https:\/\/www.smarttarif24.de\/blog\/wp-content\/uploads\/2022\/03\/New-update-1024x1024.png 1024w, https:\/\/www.smarttarif24.de\/blog\/wp-content\/uploads\/2022\/03\/New-update-150x150.png 150w, https:\/\/www.smarttarif24.de\/blog\/wp-content\/uploads\/2022\/03\/New-update-300x300.png 300w, https:\/\/www.smarttarif24.de\/blog\/wp-content\/uploads\/2022\/03\/New-update-768x768.png 768w, https:\/\/www.smarttarif24.de\/blog\/wp-content\/uploads\/2022\/03\/New-update.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Mark Zuckerberg sagte in k\u00fcrzlich in einem Interview, dass sein Konzern NFTs auf Instagram testet und dass \u201esehr \u00e4hnliche Funktionen\u201c auch bald auf Facebook verf\u00fcgbar sein sollen. Der Instagram-Chef Adam Mosseri k\u00fcndigte auf Twitter an, dass eine kleine ausgew\u00e4hlte Gruppe aus den USA die Chance haben werden, NFTs in ihrem pers\u00f6nlichen Feed ihrer Storys und in den Nachrichten anzuzeigen. Wir sind gespannt was in Zukunft die Plattform noch alles zu bieten hat.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Was ist wieder bei Instagram los? Bald euch ein Kunstportal? Eine ausgew\u00e4hlte Gruppe von K\u00fcnstlern und Sammlern aus den USA soll in K\u00fcrze die M\u00f6glichkeit&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[817,1,3],"tags":[1536,353,461,1613,1614,1611,1612,13,620,14,194],"_links":{"self":[{"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/posts\/3198"}],"collection":[{"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/comments?post=3198"}],"version-history":[{"count":1,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/posts\/3198\/revisions"}],"predecessor-version":[{"id":3199,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/posts\/3198\/revisions\/3199"}],"wp:attachment":[{"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/media?parent=3198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/categories?post=3198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/tags?post=3198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}