{"id":1929,"date":"2019-03-27T14:30:04","date_gmt":"2019-03-27T13:30:04","guid":{"rendered":"http:\/\/www.smarttarif24.de\/Blog\/?p=1929"},"modified":"2019-03-26T10:26:45","modified_gmt":"2019-03-26T09:26:45","slug":"samsung-sind-die-galaxy-buds-wasserdicht","status":"publish","type":"post","link":"https:\/\/www.smarttarif24.de\/blog\/2019\/03\/27\/samsung-sind-die-galaxy-buds-wasserdicht\/","title":{"rendered":"Samsung: Sind die Galaxy Buds Wasserdicht?"},"content":{"rendered":"<p>Nachdem wir euch ja<a href=\"http:\/\/www.smarttarif24.de\/Blog\/2019\/02\/25\/samsung-galaxy-buds\/?preview=true\"> hier<\/a> \u00fcber die Galaxy Buds berichtet hatten, kam die Frage auf ob die Buds auch wasserdicht sind?! Das kl\u00e4ren wir heute auf.<\/p>\n<p><iframe loading=\"lazy\" width=\"1160\" height=\"653\" src=\"https:\/\/www.youtube.com\/embed\/uzt2PchQAI4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>In der Auflistung der technischen Daten der kabellosen Ear-Buds steht:\u00a0IPX2-zertifiziert was genau bedeutet das?\u00a0\u00a0IPX2-zertifiziert hei\u00dft, dass die Galaxy Buds nur gegen Tropfwasser gesch\u00fctzt sind. Sie haben keine\u00a0IP68-Zertifizierung wie bei der<a href=\"https:\/\/www.smarttarif24.de\/artikel\/samsung-galaxy-s10-128gb-prism-black-mit-tarif-vodafone-smart-xl-premium.html\">\u00a0Galaxy S10-Reihe<\/a> die sind n\u00e4mlich alle wasserdicht. Daher lag es, nahe das die neuen Buds ebenfalls Wasserfest sind, das sind sie <strong>NICHT<\/strong>. Die Buds sind mit der\u00a0IPX2-zertifiziert nur gegen Schwei\u00df und Wassertropfen die Oberfl\u00e4chlich liegen gesichert. Also geht <strong>NICHT<\/strong> mit den Buds Schwimmen oder Duschen, dadurch kann die Elektronik besch\u00e4digt werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nachdem wir euch ja hier \u00fcber die Galaxy Buds berichtet hatten, kam die Frage auf ob die Buds auch wasserdicht sind?! Das kl\u00e4ren wir heute&hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6,1,3],"tags":[11,680,343,8,13,18,14,790,791],"_links":{"self":[{"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/posts\/1929"}],"collection":[{"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/comments?post=1929"}],"version-history":[{"count":4,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/posts\/1929\/revisions"}],"predecessor-version":[{"id":1934,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/posts\/1929\/revisions\/1934"}],"wp:attachment":[{"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/media?parent=1929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/categories?post=1929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/tags?post=1929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}