{"id":1826,"date":"2019-03-15T16:00:31","date_gmt":"2019-03-15T15:00:31","guid":{"rendered":"http:\/\/www.smarttarif24.de\/Blog\/?p=1826"},"modified":"2019-03-15T16:00:31","modified_gmt":"2019-03-15T15:00:31","slug":"huawei-mate-9-neues-update-verfuegbar","status":"publish","type":"post","link":"https:\/\/www.smarttarif24.de\/blog\/2019\/03\/15\/huawei-mate-9-neues-update-verfuegbar\/","title":{"rendered":"Huawei Mate 9: Neues Update verf\u00fcgbar!"},"content":{"rendered":"<figure id=\"attachment_1827\" aria-describedby=\"caption-attachment-1827\" style=\"width: 274px\" class=\"wp-caption alignnone\"><img decoding=\"async\" loading=\"lazy\" class=\" wp-image-1827\" src=\"http:\/\/www.smarttarif24.de\/Blog\/wp-content\/uploads\/2019\/03\/Huawei-Mate-9.jpg\" alt=\"\" width=\"274\" height=\"372\" \/><figcaption id=\"caption-attachment-1827\" class=\"wp-caption-text\">Quelle: consumer.huawei.com<\/figcaption><\/figure>\n<p>Das <strong>Huawei Mate 9<\/strong> ist nun fast zwei Jahre alt und bekommt endlich auch ein Update. Seit einiger Zeit stellte <strong>Huawei<\/strong> nur in China das Update zu Verf\u00fcgung. Nun ist die Aktualisierung auf Android 9.0 Pie auch in Deutschland, \u00d6sterreich und Schweiz verf\u00fcgbar.<\/p>\n<p>Die Aktualisierung beinhaltet unter anderem das Google-OS und die neuste Version der Huawei-Nutzeroberfl\u00e4che EMUI 9 mit intuitiverem Design. Der Hesteller hat auch die Systemleistung mit diesem Update verbessert. Viele Anwendungen werden jetzt schneller und fl\u00fcssiger laufen.<\/p>\n<p>Die weiteren Neuerungen von Android 9 Pie sind folgende:<\/p>\n<ul>\n<li>Ein Button und Wischgesten ersetzen drei Tasten<\/li>\n<li>Die KI soll alte Funktionen besser machen<\/li>\n<li>Quality Time mit dem Smartphone<\/li>\n<li>Kleine \u00c4nderungen in Sachen Schnelleinstellungen, Screenshot und Benachrichtigungen<\/li>\n<\/ul>\n<p>Die Aktualisierung kann aber nur \u00fcber eine App erfolgen (HiCare). Ein einfacher Klick auf den Aktualisierung-Button in der App gen\u00fcgt, um das Update zu starten. Wir empfehlen aber auch hier, erst ein Backup zu erstellen bevor man ein Update startet.<\/p>\n<p>Das Update ist fast 3,5 GB gro\u00df und sollte daher \u00fcber eine WLAN-Verbindung heruntergeladen werden.<\/p>\n<p><strong>Huawei Mate 9<\/strong> \u00fcberzeugte Ende 2016 mit seinem herausragenden Akku und dem guten Sound. Leider ist dieses Smartphone nicht wasserdicht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Huawei Mate 9 ist nun fast zwei Jahre alt und bekommt endlich auch ein Update. Seit einiger Zeit stellte Huawei nur in China das&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6,1,3,5],"tags":[11,38,36,762,732,13,472,14,194],"_links":{"self":[{"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/posts\/1826"}],"collection":[{"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/comments?post=1826"}],"version-history":[{"count":1,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/posts\/1826\/revisions"}],"predecessor-version":[{"id":1828,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/posts\/1826\/revisions\/1828"}],"wp:attachment":[{"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/media?parent=1826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/categories?post=1826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.smarttarif24.de\/blog\/wp-json\/wp\/v2\/tags?post=1826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}